{"id":76870,"date":"2020-07-01T14:29:51","date_gmt":"2020-07-01T14:29:51","guid":{"rendered":"https:\/\/intermob.be\/?post_type=product&#038;p=76870"},"modified":"2024-06-21T14:11:23","modified_gmt":"2024-06-21T14:11:23","slug":"horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm","status":"publish","type":"product","link":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/","title":{"rendered":"Terrasse Tisch - Werzalit White Block - 70x120 Cm"},"content":{"rendered":"<p><span style=\"color: #000000\">Geeignet f\u00fcr terrasse, regensicher.<\/span><\/p>\n<p><i class=\"fas fa-check-circle description-icon-green\" aria-hidden=\"true\"><\/i><span style=\"color: #ff6600\"> Die Tische sind unmontiert<\/span><br \/>\n<i class=\"fas fa-check-circle description-icon-green\" aria-hidden=\"true\"><\/i><span style=\"color: #339966\"> Die Tischplatten sind nicht vorgebohrt<\/span><br \/>\n<i class=\"fas fa-check-circle description-icon-green\" aria-hidden=\"true\"><\/i><span style=\"color: #ff6600\"> Schrauben sind inklusive, wenn die Tischplatten zusammen mit den Untergestellen bestellt werden<\/span><br \/>\n<i class=\"fas fa-check-circle description-icon-green\" aria-hidden=\"true\"><\/i><span style=\"color: #339966\"> Das zur Montage ben\u00f6tigte Material ist im Karton enthalten<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Geeignet f\u00fcr terrasse, regensicher. Die Tische sind unmontiert Die Tischplatten sind nicht vorgebohrt Schrauben sind inklusive, wenn die Tischplatten zusammen<\/p>\n","protected":false},"featured_media":76871,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[9999,10195],"product_tag":[17392,17393,17395,17388,17389,17390,17391],"class_list":["post-76870","product","type-product","status-publish","has-post-thumbnail","product_cat-werzalit-white-block-tisch-sortiment","product_cat-70x120-tische","product_tag-meubles-horeca","product_tag-restaurant-furniture","product_tag-restaurant-moebel","product_tag-horeca-furniture","product_tag-horeca-meubelen","product_tag-horeca-moebel","product_tag-meubles-de-restaurant","pa_product-frame-color-schwarz-frame-color-de","pa_product-more-colors-ja-de","pa_product-more-dimensions-ja-de","pa_product-tabletop-color-mehrfarbig-tabletop-color-de","pa_product-tabletop-color-weiss-tabletop-color-de","pa_product-usage-usage-draussen-de","pa_table-height-cm-72-cm-de","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Horeca Terrasse Tisch - Werzalit White Block - 70x120 Cm<\/title>\n<meta name=\"description\" content=\"Entdecken Sie unseren wei\u00df\/bunten Terrassentisch in Werzalit 70x120 cm mit Fu\u00df aus Aluminiumguss. Auch in anderen Formen, Gr\u00f6\u00dfen und Farben erh\u00e4ltlich.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Horeca Terrasse Tisch - Werzalit White Block - 70x120 Cm\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie unseren wei\u00df\/bunten Terrassentisch in Werzalit 70x120 cm mit Fu\u00df aus Aluminiumguss. Auch in anderen Formen, Gr\u00f6\u00dfen und Farben erh\u00e4ltlich.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/\" \/>\n<meta property=\"og:site_name\" content=\"Intermob Mobilier\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-21T14:11:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intermob.be\/wp-content\/uploads\/2024\/03\/products-Horeca-Terrastafel-Werzalit-White-Block-70\u00d7120-Cm-A-440-1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/\",\"url\":\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/\",\"name\":\"Horeca Terrasse Tisch - Werzalit White Block - 70x120 Cm\",\"isPartOf\":{\"@id\":\"https:\/\/intermob.be\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/intermob.be\/wp-content\/uploads\/2024\/03\/products-Horeca-Terrastafel-Werzalit-White-Block-70\u00d7120-Cm-A-440-1-2.jpg\",\"datePublished\":\"2020-07-01T14:29:51+00:00\",\"dateModified\":\"2024-06-21T14:11:23+00:00\",\"description\":\"Entdecken Sie unseren wei\u00df\/bunten Terrassentisch in Werzalit 70x120 cm mit Fu\u00df aus Aluminiumguss. Auch in anderen Formen, Gr\u00f6\u00dfen und Farben erh\u00e4ltlich.\",\"breadcrumb\":{\"@id\":\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/#primaryimage\",\"url\":\"https:\/\/intermob.be\/wp-content\/uploads\/2024\/03\/products-Horeca-Terrastafel-Werzalit-White-Block-70\u00d7120-Cm-A-440-1-2.jpg\",\"contentUrl\":\"https:\/\/intermob.be\/wp-content\/uploads\/2024\/03\/products-Horeca-Terrastafel-Werzalit-White-Block-70\u00d7120-Cm-A-440-1-2.jpg\",\"width\":1500,\"height\":1500,\"caption\":\"Horeca-Terrastafel-Werzalit-White-Block-70\u00d7120-Cm-A-440\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/intermob.be\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/intermob.be\/de\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Horeca Terrasse Tisch &#8211; Werzalit White Block &#8211; 70&#215;120 Cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/intermob.be\/de\/#website\",\"url\":\"https:\/\/intermob.be\/de\/\",\"name\":\"Intermob\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/intermob.be\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/intermob.be\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/intermob.be\/de\/#organization\",\"name\":\"Intermob Mobilier\",\"url\":\"https:\/\/intermob.be\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/intermob.be\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intermob.be\/wp-content\/uploads\/2025\/09\/intb-bold-logo.png\",\"contentUrl\":\"https:\/\/intermob.be\/wp-content\/uploads\/2025\/09\/intb-bold-logo.png\",\"width\":480,\"height\":158,\"caption\":\"Intermob Mobilier\"},\"image\":{\"@id\":\"https:\/\/intermob.be\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Horeca Terrasse Tisch - Werzalit White Block - 70x120 Cm","description":"Entdecken Sie unseren wei\u00df\/bunten Terrassentisch in Werzalit 70x120 cm mit Fu\u00df aus Aluminiumguss. Auch in anderen Formen, Gr\u00f6\u00dfen und Farben erh\u00e4ltlich.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/","og_locale":"de_DE","og_type":"article","og_title":"Horeca Terrasse Tisch - Werzalit White Block - 70x120 Cm","og_description":"Entdecken Sie unseren wei\u00df\/bunten Terrassentisch in Werzalit 70x120 cm mit Fu\u00df aus Aluminiumguss. Auch in anderen Formen, Gr\u00f6\u00dfen und Farben erh\u00e4ltlich.","og_url":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/","og_site_name":"Intermob Mobilier","article_modified_time":"2024-06-21T14:11:23+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/intermob.be\/wp-content\/uploads\/2024\/03\/products-Horeca-Terrastafel-Werzalit-White-Block-70\u00d7120-Cm-A-440-1-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/","url":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/","name":"Horeca Terrasse Tisch - Werzalit White Block - 70x120 Cm","isPartOf":{"@id":"https:\/\/intermob.be\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/#primaryimage"},"image":{"@id":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/#primaryimage"},"thumbnailUrl":"https:\/\/intermob.be\/wp-content\/uploads\/2024\/03\/products-Horeca-Terrastafel-Werzalit-White-Block-70\u00d7120-Cm-A-440-1-2.jpg","datePublished":"2020-07-01T14:29:51+00:00","dateModified":"2024-06-21T14:11:23+00:00","description":"Entdecken Sie unseren wei\u00df\/bunten Terrassentisch in Werzalit 70x120 cm mit Fu\u00df aus Aluminiumguss. Auch in anderen Formen, Gr\u00f6\u00dfen und Farben erh\u00e4ltlich.","breadcrumb":{"@id":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/#primaryimage","url":"https:\/\/intermob.be\/wp-content\/uploads\/2024\/03\/products-Horeca-Terrastafel-Werzalit-White-Block-70\u00d7120-Cm-A-440-1-2.jpg","contentUrl":"https:\/\/intermob.be\/wp-content\/uploads\/2024\/03\/products-Horeca-Terrastafel-Werzalit-White-Block-70\u00d7120-Cm-A-440-1-2.jpg","width":1500,"height":1500,"caption":"Horeca-Terrastafel-Werzalit-White-Block-70\u00d7120-Cm-A-440"},{"@type":"BreadcrumbList","@id":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-block-weiss-70-120-cm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intermob.be\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/intermob.be\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Horeca Terrasse Tisch &#8211; Werzalit White Block &#8211; 70&#215;120 Cm"}]},{"@type":"WebSite","@id":"https:\/\/intermob.be\/de\/#website","url":"https:\/\/intermob.be\/de\/","name":"Intermob","description":"","publisher":{"@id":"https:\/\/intermob.be\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intermob.be\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/intermob.be\/de\/#organization","name":"Intermob Mobilier","url":"https:\/\/intermob.be\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/intermob.be\/de\/#\/schema\/logo\/image\/","url":"https:\/\/intermob.be\/wp-content\/uploads\/2025\/09\/intb-bold-logo.png","contentUrl":"https:\/\/intermob.be\/wp-content\/uploads\/2025\/09\/intb-bold-logo.png","width":480,"height":158,"caption":"Intermob Mobilier"},"image":{"@id":"https:\/\/intermob.be\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product\/76870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/comments?post=76870"}],"version-history":[{"count":0,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product\/76870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/media\/76871"}],"wp:attachment":[{"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/media?parent=76870"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product_brand?post=76870"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product_cat?post=76870"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product_tag?post=76870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}