{"id":81346,"date":"2021-10-15T10:16:44","date_gmt":"2021-10-15T10:16:44","guid":{"rendered":"https:\/\/intermob.be\/?post_type=product&#038;p=81346"},"modified":"2026-07-21T11:58:33","modified_gmt":"2026-07-21T11:58:33","slug":"horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2","status":"publish","type":"product","link":"https:\/\/intermob.be\/de\/produkt\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\/","title":{"rendered":"Runder Tisch - Madrid K4 - 110 Cm"},"content":{"rendered":"<p><i class=\"fas fa-check-circle description-icon-green\" aria-hidden=\"true\"><\/i><span style=\"color: #ff6600\"> Die Tische sind unmontiert<\/span><br \/>\n<i class=\"fas fa-check-circle description-icon-green\" aria-hidden=\"true\"><\/i><span style=\"color: #339966\"> Die Tischplatten sind nicht vorgebohrt<\/span><br \/>\n<i class=\"fas fa-check-circle description-icon-green\" aria-hidden=\"true\"><\/i><span style=\"color: #ff6600\"> Schrauben sind inklusive, wenn die Tischplatten zusammen mit den Untergestellen bestellt werden<\/span><br \/>\n<i class=\"fas fa-check-circle description-icon-green\" aria-hidden=\"true\"><\/i><span style=\"color: #339966\"> Das zur Montage ben\u00f6tigte Material ist im Karton enthalten<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Tische sind unmontiert Die Tischplatten sind nicht vorgebohrt Schrauben sind inklusive, wenn die Tischplatten zusammen mit den Untergestellen bestellt<\/p>\n","protected":false},"featured_media":81347,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[10143,9995],"product_tag":[17391,17393,17395],"class_list":["post-81346","product","type-product","status-publish","has-post-thumbnail","product_cat-madrid-k4-tisch-sortiment","product_cat-runde-tische","product_tag-meubles-de-restaurant","product_tag-restaurant-furniture","product_tag-restaurant-moebel","pa_product-frame-color-schwarz-frame-color-de","pa_product-more-colors-ja-de","pa_product-more-dimensions-ja-de","pa_product-seats-4-seats-de","pa_product-tabletop-color-holzoptik-tabletop-color-de","pa_product-usage-usage-innen-de","pa_table-height-cm-7530-cm-de","first","outofstock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Horeca Runder Tisch - Madrid K4 - 110 Cm Mit Basis<\/title>\n<meta name=\"description\" content=\"Entdecken Sie unseren Madrid K4 Runder Tisch 110 cm aus Melamin auf Gusseisenbasis. Erh\u00e4ltlich in verschiedenen Farben, Formen und Gr\u00f6\u00dfen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intermob.be\/de\/produkt\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Horeca Runder Tisch - Madrid K4 - 110 Cm Mit Basis\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie unseren Madrid K4 Runder Tisch 110 cm aus Melamin auf Gusseisenbasis. Erh\u00e4ltlich in verschiedenen Farben, Formen und Gr\u00f6\u00dfen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intermob.be\/de\/produkt\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Intermob Mobilier\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-21T11:58:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intermob.be\/wp-content\/uploads\/2024\/04\/products-Horeca-Tafel-Rond-Madrid-K4-110-Cm-Met-Onderstel-B-311-105-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/intermob.be\\\/de\\\/produkt\\\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\\\/\",\"url\":\"https:\\\/\\\/intermob.be\\\/de\\\/produkt\\\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\\\/\",\"name\":\"Horeca Runder Tisch - Madrid K4 - 110 Cm Mit Basis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intermob.be\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/intermob.be\\\/de\\\/produkt\\\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/intermob.be\\\/de\\\/produkt\\\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/intermob.be\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/products-Horeca-Tafel-Rond-Madrid-K4-110-Cm-Met-Onderstel-B-311-105-2.jpg\",\"datePublished\":\"2021-10-15T10:16:44+00:00\",\"dateModified\":\"2026-07-21T11:58:33+00:00\",\"description\":\"Entdecken Sie unseren Madrid K4 Runder Tisch 110 cm aus Melamin auf Gusseisenbasis. Erh\u00e4ltlich in verschiedenen Farben, Formen und Gr\u00f6\u00dfen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/intermob.be\\\/de\\\/produkt\\\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/intermob.be\\\/de\\\/produkt\\\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/intermob.be\\\/de\\\/produkt\\\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/intermob.be\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/products-Horeca-Tafel-Rond-Madrid-K4-110-Cm-Met-Onderstel-B-311-105-2.jpg\",\"contentUrl\":\"https:\\\/\\\/intermob.be\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/products-Horeca-Tafel-Rond-Madrid-K4-110-Cm-Met-Onderstel-B-311-105-2.jpg\",\"width\":1500,\"height\":1500,\"caption\":\"Horeca-Tafel-Rond-Madrid-K4-110-Cm-Met-Onderstel-B-311-105\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/intermob.be\\\/de\\\/produkt\\\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/intermob.be\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/intermob.be\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Horeca Runder Tisch &#8211; Madrid K4 &#8211; 110 Cm Mit Basis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/intermob.be\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/intermob.be\\\/de\\\/\",\"name\":\"Intermob Mobilier\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/intermob.be\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/intermob.be\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/intermob.be\\\/de\\\/#organization\",\"name\":\"Intermob Mobilier\",\"url\":\"https:\\\/\\\/intermob.be\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/intermob.be\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/intermob.be\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/intb-bold-logo.png\",\"contentUrl\":\"https:\\\/\\\/intermob.be\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/intb-bold-logo.png\",\"width\":480,\"height\":158,\"caption\":\"Intermob Mobilier\"},\"image\":{\"@id\":\"https:\\\/\\\/intermob.be\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Horeca Runder Tisch - Madrid K4 - 110 Cm Mit Basis","description":"Entdecken Sie unseren Madrid K4 Runder Tisch 110 cm aus Melamin auf Gusseisenbasis. Erh\u00e4ltlich in verschiedenen Farben, Formen und Gr\u00f6\u00dfen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intermob.be\/de\/produkt\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\/","og_locale":"de_DE","og_type":"article","og_title":"Horeca Runder Tisch - Madrid K4 - 110 Cm Mit Basis","og_description":"Entdecken Sie unseren Madrid K4 Runder Tisch 110 cm aus Melamin auf Gusseisenbasis. Erh\u00e4ltlich in verschiedenen Farben, Formen und Gr\u00f6\u00dfen.","og_url":"https:\/\/intermob.be\/de\/produkt\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\/","og_site_name":"Intermob Mobilier","article_modified_time":"2026-07-21T11:58:33+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/intermob.be\/wp-content\/uploads\/2024\/04\/products-Horeca-Tafel-Rond-Madrid-K4-110-Cm-Met-Onderstel-B-311-105-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/intermob.be\/de\/produkt\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\/","url":"https:\/\/intermob.be\/de\/produkt\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\/","name":"Horeca Runder Tisch - Madrid K4 - 110 Cm Mit Basis","isPartOf":{"@id":"https:\/\/intermob.be\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intermob.be\/de\/produkt\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\/#primaryimage"},"image":{"@id":"https:\/\/intermob.be\/de\/produkt\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\/#primaryimage"},"thumbnailUrl":"https:\/\/intermob.be\/wp-content\/uploads\/2024\/04\/products-Horeca-Tafel-Rond-Madrid-K4-110-Cm-Met-Onderstel-B-311-105-2.jpg","datePublished":"2021-10-15T10:16:44+00:00","dateModified":"2026-07-21T11:58:33+00:00","description":"Entdecken Sie unseren Madrid K4 Runder Tisch 110 cm aus Melamin auf Gusseisenbasis. Erh\u00e4ltlich in verschiedenen Farben, Formen und Gr\u00f6\u00dfen.","breadcrumb":{"@id":"https:\/\/intermob.be\/de\/produkt\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intermob.be\/de\/produkt\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/intermob.be\/de\/produkt\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\/#primaryimage","url":"https:\/\/intermob.be\/wp-content\/uploads\/2024\/04\/products-Horeca-Tafel-Rond-Madrid-K4-110-Cm-Met-Onderstel-B-311-105-2.jpg","contentUrl":"https:\/\/intermob.be\/wp-content\/uploads\/2024\/04\/products-Horeca-Tafel-Rond-Madrid-K4-110-Cm-Met-Onderstel-B-311-105-2.jpg","width":1500,"height":1500,"caption":"Horeca-Tafel-Rond-Madrid-K4-110-Cm-Met-Onderstel-B-311-105"},{"@type":"BreadcrumbList","@id":"https:\/\/intermob.be\/de\/produkt\/horeca-runder-tisch-madrid-k4-110-cm-mit-basis-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intermob.be\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/intermob.be\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Horeca Runder Tisch &#8211; Madrid K4 &#8211; 110 Cm Mit Basis"}]},{"@type":"WebSite","@id":"https:\/\/intermob.be\/de\/#website","url":"https:\/\/intermob.be\/de\/","name":"Intermob Mobilier","description":"","publisher":{"@id":"https:\/\/intermob.be\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intermob.be\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/intermob.be\/de\/#organization","name":"Intermob Mobilier","url":"https:\/\/intermob.be\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/intermob.be\/de\/#\/schema\/logo\/image\/","url":"https:\/\/intermob.be\/wp-content\/uploads\/2025\/09\/intb-bold-logo.png","contentUrl":"https:\/\/intermob.be\/wp-content\/uploads\/2025\/09\/intb-bold-logo.png","width":480,"height":158,"caption":"Intermob Mobilier"},"image":{"@id":"https:\/\/intermob.be\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product\/81346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/comments?post=81346"}],"version-history":[{"count":0,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product\/81346\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/media\/81347"}],"wp:attachment":[{"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/media?parent=81346"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product_brand?post=81346"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product_cat?post=81346"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product_tag?post=81346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}