{"id":83748,"date":"2022-05-25T13:30:07","date_gmt":"2022-05-25T13:30:07","guid":{"rendered":"https:\/\/intermob.be\/?post_type=product&#038;p=83748"},"modified":"2024-06-21T09:13:59","modified_gmt":"2024-06-21T09:13:59","slug":"horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3","status":"publish","type":"product","link":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/","title":{"rendered":"Terrasse Tisch - Werzalit Indian Shesman - 60x60 Cm"},"content":{"rendered":"<p><span style=\"color: #000000\">Geeignet f\u00fcr terrasse, regensicher.<\/span><\/p>\n<p><i class=\"fas fa-check-circle description-icon-green\" aria-hidden=\"true\"><\/i><span style=\"color: #ff6600\"> Die Tische sind unmontiert<\/span><br \/>\n<i class=\"fas fa-check-circle description-icon-green\" aria-hidden=\"true\"><\/i><span style=\"color: #339966\"> Die Tischplatten sind nicht vorgebohrt<\/span><br \/>\n<i class=\"fas fa-check-circle description-icon-green\" aria-hidden=\"true\"><\/i><span style=\"color: #ff6600\"> Schrauben sind inklusive, wenn die Tischplatten zusammen mit den Untergestellen bestellt werden<\/span><br \/>\n<i class=\"fas fa-check-circle description-icon-green\" aria-hidden=\"true\"><\/i><span style=\"color: #339966\"> Das zur Montage ben\u00f6tigte Material ist im Karton enthalten<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Geeignet f\u00fcr terrasse, regensicher. Die Tische sind unmontiert Die Tischplatten sind nicht vorgebohrt Schrauben sind inklusive, wenn die Tischplatten zusammen<\/p>\n","protected":false},"featured_media":83563,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[9955,10183],"product_tag":[17388,17389,17390,17391,17392,17393,17395],"class_list":{"0":"post-83748","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-werzalit-is-tisch-sortiment","7":"product_cat-70x70-tische","8":"product_tag-horeca-furniture","9":"product_tag-horeca-meubelen","10":"product_tag-horeca-moebel","11":"product_tag-meubles-de-restaurant","12":"product_tag-meubles-horeca","13":"product_tag-restaurant-furniture","14":"product_tag-restaurant-moebel","15":"pa_product-frame-color-schwarz-frame-color-de","16":"pa_product-more-colors-ja-de","17":"pa_product-more-dimensions-ja-de","18":"pa_product-tabletop-color-holzoptik-tabletop-color-de","19":"pa_product-usage-usage-draussen-de","20":"pa_table-height-cm-75-cm-de","22":"first","23":"outofstock","24":"sale","25":"taxable","26":"shipping-taxable","27":"purchasable","28":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Horeca Terrasse Tisch - Werzalit Indian Shesman - 60x60 Cm<\/title>\n<meta name=\"description\" content=\"Entdecken Sie unseren Terrassentisch in Holzoptik in Werzalit 60x60 cm mit Fu\u00df aus Gusseisen. Auch in anderen Formen, Gr\u00f6\u00dfen und Farben erh\u00e4ltlich.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Horeca Terrasse Tisch - Werzalit Indian Shesman - 60x60 Cm\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie unseren Terrassentisch in Holzoptik in Werzalit 60x60 cm mit Fu\u00df aus Gusseisen. Auch in anderen Formen, Gr\u00f6\u00dfen und Farben erh\u00e4ltlich.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Intermob Mobilier\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-21T09:13:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intermob.be\/wp-content\/uploads\/2024\/04\/products-Horeca-Terrastafel-Werzalit-Indian-Shesman-60\u00d760-Cm-B-CE155-1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/\",\"url\":\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/\",\"name\":\"Horeca Terrasse Tisch - Werzalit Indian Shesman - 60x60 Cm\",\"isPartOf\":{\"@id\":\"https:\/\/intermob.be\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/intermob.be\/wp-content\/uploads\/2024\/04\/products-Horeca-Terrastafel-Werzalit-Indian-Shesman-60\u00d760-Cm-B-CE155-1-2.jpg\",\"datePublished\":\"2022-05-25T13:30:07+00:00\",\"dateModified\":\"2024-06-21T09:13:59+00:00\",\"description\":\"Entdecken Sie unseren Terrassentisch in Holzoptik in Werzalit 60x60 cm mit Fu\u00df aus Gusseisen. Auch in anderen Formen, Gr\u00f6\u00dfen und Farben erh\u00e4ltlich.\",\"breadcrumb\":{\"@id\":\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/#primaryimage\",\"url\":\"https:\/\/intermob.be\/wp-content\/uploads\/2024\/04\/products-Horeca-Terrastafel-Werzalit-Indian-Shesman-60\u00d760-Cm-B-CE155-1-2.jpg\",\"contentUrl\":\"https:\/\/intermob.be\/wp-content\/uploads\/2024\/04\/products-Horeca-Terrastafel-Werzalit-Indian-Shesman-60\u00d760-Cm-B-CE155-1-2.jpg\",\"width\":1500,\"height\":1500,\"caption\":\"Horeca-Terrastafel-Werzalit-Indian-Shesman-60\u00d760-Cm-B-CE155\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/intermob.be\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/intermob.be\/de\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Horeca Terrasse Tisch &#8211; Werzalit Indian Shesman &#8211; 60&#215;60 Cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/intermob.be\/de\/#website\",\"url\":\"https:\/\/intermob.be\/de\/\",\"name\":\"Intermob\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/intermob.be\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/intermob.be\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/intermob.be\/de\/#organization\",\"name\":\"Intermob Mobilier\",\"url\":\"https:\/\/intermob.be\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/intermob.be\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intermob.be\/wp-content\/uploads\/2025\/09\/intb-bold-logo.png\",\"contentUrl\":\"https:\/\/intermob.be\/wp-content\/uploads\/2025\/09\/intb-bold-logo.png\",\"width\":480,\"height\":158,\"caption\":\"Intermob Mobilier\"},\"image\":{\"@id\":\"https:\/\/intermob.be\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Horeca Terrasse Tisch - Werzalit Indian Shesman - 60x60 Cm","description":"Entdecken Sie unseren Terrassentisch in Holzoptik in Werzalit 60x60 cm mit Fu\u00df aus Gusseisen. Auch in anderen Formen, Gr\u00f6\u00dfen und Farben erh\u00e4ltlich.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/","og_locale":"de_DE","og_type":"article","og_title":"Horeca Terrasse Tisch - Werzalit Indian Shesman - 60x60 Cm","og_description":"Entdecken Sie unseren Terrassentisch in Holzoptik in Werzalit 60x60 cm mit Fu\u00df aus Gusseisen. Auch in anderen Formen, Gr\u00f6\u00dfen und Farben erh\u00e4ltlich.","og_url":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/","og_site_name":"Intermob Mobilier","article_modified_time":"2024-06-21T09:13:59+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/intermob.be\/wp-content\/uploads\/2024\/04\/products-Horeca-Terrastafel-Werzalit-Indian-Shesman-60\u00d760-Cm-B-CE155-1-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/","url":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/","name":"Horeca Terrasse Tisch - Werzalit Indian Shesman - 60x60 Cm","isPartOf":{"@id":"https:\/\/intermob.be\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/#primaryimage"},"image":{"@id":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/#primaryimage"},"thumbnailUrl":"https:\/\/intermob.be\/wp-content\/uploads\/2024\/04\/products-Horeca-Terrastafel-Werzalit-Indian-Shesman-60\u00d760-Cm-B-CE155-1-2.jpg","datePublished":"2022-05-25T13:30:07+00:00","dateModified":"2024-06-21T09:13:59+00:00","description":"Entdecken Sie unseren Terrassentisch in Holzoptik in Werzalit 60x60 cm mit Fu\u00df aus Gusseisen. Auch in anderen Formen, Gr\u00f6\u00dfen und Farben erh\u00e4ltlich.","breadcrumb":{"@id":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/#primaryimage","url":"https:\/\/intermob.be\/wp-content\/uploads\/2024\/04\/products-Horeca-Terrastafel-Werzalit-Indian-Shesman-60\u00d760-Cm-B-CE155-1-2.jpg","contentUrl":"https:\/\/intermob.be\/wp-content\/uploads\/2024\/04\/products-Horeca-Terrastafel-Werzalit-Indian-Shesman-60\u00d760-Cm-B-CE155-1-2.jpg","width":1500,"height":1500,"caption":"Horeca-Terrastafel-Werzalit-Indian-Shesman-60\u00d760-Cm-B-CE155"},{"@type":"BreadcrumbList","@id":"https:\/\/intermob.be\/de\/produkt\/horeca-terrasse-tisch-werzalit-indian-shesman-60x60-cm-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intermob.be\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/intermob.be\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Horeca Terrasse Tisch &#8211; Werzalit Indian Shesman &#8211; 60&#215;60 Cm"}]},{"@type":"WebSite","@id":"https:\/\/intermob.be\/de\/#website","url":"https:\/\/intermob.be\/de\/","name":"Intermob","description":"","publisher":{"@id":"https:\/\/intermob.be\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intermob.be\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/intermob.be\/de\/#organization","name":"Intermob Mobilier","url":"https:\/\/intermob.be\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/intermob.be\/de\/#\/schema\/logo\/image\/","url":"https:\/\/intermob.be\/wp-content\/uploads\/2025\/09\/intb-bold-logo.png","contentUrl":"https:\/\/intermob.be\/wp-content\/uploads\/2025\/09\/intb-bold-logo.png","width":480,"height":158,"caption":"Intermob Mobilier"},"image":{"@id":"https:\/\/intermob.be\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product\/83748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/comments?post=83748"}],"version-history":[{"count":0,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product\/83748\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/media\/83563"}],"wp:attachment":[{"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/media?parent=83748"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product_brand?post=83748"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product_cat?post=83748"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/intermob.be\/de\/wp-json\/wp\/v2\/product_tag?post=83748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}